{"id":11347,"date":"2013-03-12T22:09:28","date_gmt":"2013-03-12T22:09:28","guid":{"rendered":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2.jpg"},"modified":"2013-03-12T22:09:28","modified_gmt":"2013-03-12T22:09:28","slug":"jj_06-3","status":"inherit","type":"attachment","link":"http:\/\/www.julianajabour.com.br\/blog\/jj_06-3\/","title":{"rendered":"jj_06"},"author":1,"comment_status":"open","ping_status":"open","template":"","meta":[],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2.jpg'><img width=\"240\" height=\"300\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2-240x300.jpg 240w, http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2.jpg 600w\" sizes=\"(max-width: 240px) 100vw, 240px\" style=\"width:100%;height:125%;max-width:600px;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":750,"file":"2013\/03\/jj_062-2.jpg","sizes":{"thumbnail":{"file":"jj_062-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2-150x150.jpg"},"medium":{"file":"jj_062-2-240x300.jpg","width":240,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2-240x300.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"jj_062-2-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2-100x100.jpg"},"full":{"file":"jj_062-2.jpg","width":600,"height":750,"mime_type":"image\/jpeg","source_url":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2013\/03\/jj_062-2.jpg","_links":{"self":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/media\/11347"}],"collection":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/comments?post=11347"}]}}