{"id":3384,"date":"2011-02-10T12:22:15","date_gmt":"2011-02-10T14:22:15","guid":{"rendered":"http:\/\/www.julianajabour.com.br\/blog\/?p=3384"},"modified":"2011-02-10T12:22:15","modified_gmt":"2011-02-10T14:22:15","slug":"kanye-west-by-karl-lagerfeld-na-vman","status":"publish","type":"post","link":"http:\/\/www.julianajabour.com.br\/blog\/2011\/02\/10\/kanye-west-by-karl-lagerfeld-na-vman\/","title":{"rendered":"Kanye West by Karl Lagerfeld na Vman"},"content":{"rendered":"<p style=\"text-align: justify;\">A revista<strong> VMan<\/strong> de fevereiro traz\u00a0<strong>Kanye West<\/strong> clicado por ningu\u00e9m menos que\u00a0<strong>Karl Lagerfeld<\/strong>. A capa<strong> <\/strong>est\u00e1 dando o que falar, pois h\u00e1 rumores que cada edi\u00e7\u00e3o trar\u00e1 uma nota verdadeira de um d\u00f3lar colada na boca de Kanye. A a\u00e7\u00e3o tem tudo a ver com o cantor que adora se gabar pelos milh\u00f5es que tem.<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-3396\" title=\"kanye-west-vman-magazine-1\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2011\/02\/kanye-west-vman-magazine-1.jpg\" alt=\"\" width=\"540\" height=\"410\" \/><br \/>\nVeja o v\u00eddeo de divulga\u00e7\u00e3o da edi\u00e7\u00e3o abaixo:<\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"488\" height=\"275\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=19565966&amp;server=vimeo.com&amp;show_title=0&amp;show_byline=1&amp;show_portrait=0&amp;color=ffffff&amp;fullscreen=1&amp;autoplay=0&amp;loop=0\" \/><embed type=\"application\/x-shockwave-flash\" width=\"488\" height=\"275\" src=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=19565966&amp;server=vimeo.com&amp;show_title=0&amp;show_byline=1&amp;show_portrait=0&amp;color=ffffff&amp;fullscreen=1&amp;autoplay=0&amp;loop=0\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><br \/>\n<a href=\"http:\/\/vimeo.com\/19565966\">VMAN 21 ASSEMBLY LINE<\/a> from <a href=\"http:\/\/vimeo.com\/user2820076\">V Magazine<\/a> on <a href=\"http:\/\/vimeo.com\">Vimeo<\/a>.<br \/>\n<a href=\"http:\/\/www.highsnobiety.com\/news\/2011\/02\/04\/video-vman-21-kanye-west-by-karl-lagerfeld\/\" target=\"_blank\"><strong>Via.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A revista VMan de fevereiro traz\u00a0Kanye West clicado por ningu\u00e9m menos que\u00a0Karl Lagerfeld. A capa est\u00e1 dando o que falar, pois h\u00e1 rumores que cada edi\u00e7\u00e3o trar\u00e1 uma nota verdadeira de um d\u00f3lar colada na boca de Kanye. A a\u00e7\u00e3o tem tudo a ver com o cantor que adora se gabar pelos milh\u00f5es que tem.&hellip; <a class=\"more-link\" href=\"http:\/\/www.julianajabour.com.br\/blog\/2011\/02\/10\/kanye-west-by-karl-lagerfeld-na-vman\/\">Continuar lendo <span class=\"screen-reader-text\">Kanye West by Karl Lagerfeld na Vman<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33,96],"tags":[838,839,276,840],"acf":{"post_chamada":null},"_links":{"self":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts\/3384"}],"collection":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3384"}],"version-history":[{"count":0,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts\/3384\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3384"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}