{"id":8583,"date":"2010-05-10T18:21:11","date_gmt":"2010-05-10T20:21:11","guid":{"rendered":"http:\/\/www.julianajabour.com.br\/blog\/?p=688"},"modified":"2010-05-10T18:21:11","modified_gmt":"2010-05-10T20:21:11","slug":"arte-com-facas","status":"publish","type":"post","link":"http:\/\/www.julianajabour.com.br\/blog\/2010\/05\/10\/arte-com-facas\/","title":{"rendered":"Arte com facas"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"www.markevansart.com\" target=\"_blank\"><strong>Mark Evans<\/strong><\/a> apresenta-se dizendo que n\u00e3o sabe pintar, mas usa facas. Mas n\u00e3o se assuste! O artista usa facas para esculpir fotos e figuras de grandes personalidades em couro. Gra\u00e7as a diferen\u00e7a de tons entre o couro raspado e o couro natural curtido, Mark consegue obter varia\u00e7\u00f5es tonais, criando retratos e imagens bem realistas.<\/p>\n<p style=\"text-align: justify;\">Confira alguns trabalhos dele:<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-693\" title=\"Untitled-51\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2010\/05\/Untitled-51.jpg\" alt=\"\" width=\"600\" height=\"596\" \/><br \/>\n<img loading=\"lazy\" class=\"aligncenter size-full wp-image-691\" title=\"Untitled-13\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2010\/05\/Untitled-13.jpg\" alt=\"\" width=\"600\" height=\"393\" \/><br \/>\n<img loading=\"lazy\" class=\"aligncenter size-full wp-image-690\" title=\"Untitled-4\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2010\/05\/Untitled-4.jpg\" alt=\"\" width=\"600\" height=\"393\" \/><br \/>\n<img loading=\"lazy\" class=\"aligncenter size-full wp-image-689\" title=\"markevans2-550x263\" src=\"http:\/\/www.julianajabour.com.br\/blog\/wp-content\/uploads\/2010\/05\/markevans2-550x263.jpg\" alt=\"\" width=\"600\" height=\"287\" \/><br \/>\nPara ver mais, visite o site <a href=\"http:\/\/www.markevansart.com\" target=\"_blank\"><strong>Mark Evans.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mark Evans apresenta-se dizendo que n\u00e3o sabe pintar, mas usa facas. Mas n\u00e3o se assuste! O artista usa facas para esculpir fotos e figuras de grandes personalidades em couro. Gra\u00e7as a diferen\u00e7a de tons entre o couro raspado e o couro natural curtido, Mark consegue obter varia\u00e7\u00f5es tonais, criando retratos e imagens bem realistas. Confira&hellip; <a class=\"more-link\" href=\"http:\/\/www.julianajabour.com.br\/blog\/2010\/05\/10\/arte-com-facas\/\">Continuar lendo <span class=\"screen-reader-text\">Arte com facas<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35],"tags":[142,143,144,145],"acf":{"post_chamada":null},"_links":{"self":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts\/8583"}],"collection":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/comments?post=8583"}],"version-history":[{"count":0,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/posts\/8583\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/media?parent=8583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/categories?post=8583"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.julianajabour.com.br\/blog\/wp-json\/wp\/v2\/tags?post=8583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}